{"id":36348,"date":"2019-09-25T12:56:28","date_gmt":"2019-09-25T10:56:28","guid":{"rendered":"https:\/\/www.omniquest.de\/marktforschung-news\/?p=36348"},"modified":"2019-09-25T12:56:32","modified_gmt":"2019-09-25T10:56:32","slug":"65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests","status":"publish","type":"post","link":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests","title":{"rendered":"65% bef\u00fcrworten Kosten\u00fcbernahme durch Krankenkassen f\u00fcr Trisomie-Tests"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;3.22&#8243; bb_built=&#8220;1&#8243; _i=&#8220;0&#8243; _address=&#8220;0&#8243;][et_pb_row _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; _i=&#8220;0&#8243; _address=&#8220;0.0&#8243;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; _i=&#8220;0&#8243; _address=&#8220;0.0.0&#8243; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Fragetext&#8220; _builder_version=&#8220;3.29.3&#8243; hover_enabled=&#8220;0&#8243; border_style=&#8220;solid&#8220; _i=&#8220;0&#8243; _address=&#8220;0.0.0.0&#8243;]Nach einer Entscheidung des Gemeinsamen Bundesausschusses sollen Krankenkassen in Einzelf\u00e4llen wie Risikoschwangerschaften die Kosten f\u00fcr Trisomie-Bluttests \u00fcbernehmen k\u00f6nnen. F\u00fcr die Schwangeren liegen die Kosten bisher je nach Anbieter zwischen 130 und 540 Euro. Die bekannteste Form der Trisomie verursacht das Down-Syndrom, Kritiker bef\u00fcrchten nun fl\u00e4chendeckende Screenings in der Schwangerschaft und vermehrte Abtreibungen.  Wie stehen Sie zu der Kosten\u00fcbernahme durch die Krankenkassen?[\/et_pb_text][et_pb_counters bar_bg_color=&#8220;#38b400&#8243; _builder_version=&#8220;3.29.3&#8243; hover_enabled=&#8220;0&#8243; border_style=&#8220;solid&#8220; border_radius=&#8220;0&#8243; _i=&#8220;1&#8243; _address=&#8220;0.0.0.1&#8243;][et_pb_counter percent=&#8220;65&#8243; _builder_version=&#8220;3.29.3&#8243; title_font=&#8220;||||&#8220; percent_font=&#8220;||||&#8220; hover_enabled=&#8220;0&#8243; background_color_default=&#8220;#dddddd&#8220; parallax_default=&#8220;off&#8220; parallax_method_default=&#8220;on&#8220; bar_background_color_default=&#8220;#38b400&#8243; use_percentages=&#8220;on&#8220; border_radius=&#8220;0&#8243; allow_player_pause_default=&#8220;off&#8220; _i=&#8220;0&#8243; _address=&#8220;0.0.0.1.0&#8243; background_enable_color_default=&#8220;on&#8220;]<\/p>\n<p>Bef\u00fcrworte ich<\/p>\n<p>[\/et_pb_counter][et_pb_counter percent=&#8220;18&#8243; _builder_version=&#8220;3.29.3&#8243; title_font=&#8220;||||&#8220; percent_font=&#8220;||||&#8220; hover_enabled=&#8220;0&#8243; background_color_default=&#8220;#dddddd&#8220; parallax_default=&#8220;off&#8220; parallax_method_default=&#8220;on&#8220; bar_background_color_default=&#8220;#38b400&#8243; use_percentages=&#8220;on&#8220; border_radius=&#8220;0&#8243; allow_player_pause_default=&#8220;off&#8220; _i=&#8220;1&#8243; _address=&#8220;0.0.0.1.1&#8243; background_enable_color_default=&#8220;on&#8220;]<\/p>\n<p>Lehne ich ab<\/p>\n<p>[\/et_pb_counter][et_pb_counter percent=&#8220;17&#8243; _builder_version=&#8220;3.29.3&#8243; title_font=&#8220;||||&#8220; percent_font=&#8220;||||&#8220; hover_enabled=&#8220;0&#8243; background_color_default=&#8220;#dddddd&#8220; parallax_default=&#8220;off&#8220; parallax_method_default=&#8220;on&#8220; bar_background_color_default=&#8220;#38b400&#8243; use_percentages=&#8220;on&#8220; border_radius=&#8220;0&#8243; allow_player_pause_default=&#8220;off&#8220; _i=&#8220;2&#8243; _address=&#8220;0.0.0.1.2&#8243; background_enable_color_default=&#8220;on&#8220;]Bin mir nicht sicher[\/et_pb_counter][\/et_pb_counters][et_pb_text _builder_version=&#8220;3.29.3&#8243; hover_enabled=&#8220;0&#8243; border_style=&#8220;solid&#8220; _i=&#8220;2&#8243; _address=&#8220;0.0.0.2&#8243;]<\/p>\n<p>359 Teilnehmer<\/p>\n<p>Erhebungszeitraum: 20.09.2019 \u2013 25.09.2019<\/p>\n<p><span style=\"color: #ff8b00;\">Der Quick Poll ist ein Instrument zur kurzfristigen Trendmessung unter beliebigen Teilnehmern aus dem <a class=\"news_beitrag_link\" href=\"http:\/\/www.omniquest.de\/omnipanel\">OmniPanel<\/a> und beansprucht keine <a class=\"news_beitrag_link\" href=\"http:\/\/www.omniquest.de\/repraesentativitaet\">Repr\u00e4sentativit\u00e4t<\/a> f\u00fcr sich.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach einer Entscheidung des Gemeinsamen Bundesausschusses sollen Krankenkassen in Einzelf\u00e4llen wie Risikoschwangerschaften die Kosten f\u00fcr Trisomie-Bluttests \u00fcbernehmen k\u00f6nnen. F\u00fcr die Schwangeren liegen die Kosten bisher je nach Anbieter zwischen 130 und 540 Euro. Die bekannteste Form der Trisomie verursacht das Down-Syndrom, Kritiker bef\u00fcrchten nun fl\u00e4chendeckende Screenings in der Schwangerschaft und vermehrte Abtreibungen. Wie stehen Sie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[41],"tags":[533,63,524,444,724],"class_list":["post-36348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesellschaft","tag-bluttest","tag-geld","tag-krankenkasse","tag-schwangerschaft","tag-trisomie","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Umfrage - Kosten\u00fcbernahme von Trisomie-Test durch Krankenkassen?<\/title>\n<meta name=\"description\" content=\"Umfrage zum Thema Trisomie-Test - ... Entscheidung des Bundesausschusses ... Krankenkassen ... die Kosten f\u00fcr Trisomie-Bluttests \u00fcbernehmen ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OmniQuest-Umfrage: 65% bef\u00fcrworten Kosten\u00fcbernahme durch Krankenkassen f\u00fcr Trisomie-Tests\" \/>\n<meta property=\"og:description\" content=\"Nach einer Entscheidung des Gemeinsamen Bundesausschusses sollen Krankenkassen in Einzelf\u00e4llen wie Risikoschwangerschaften die Kosten f\u00fcr Trisomie-Bluttests \u00fcbernehmen ... | 25. September 2019\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests\" \/>\n<meta property=\"og:site_name\" content=\"OmniQuest News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/omniquest\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-25T10:56:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-25T10:56:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/09\/Bluttest2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maxkunz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"OmniQuest-Umfrage: 65% bef\u00fcrworten Kosten\u00fcbernahme durch Krankenkassen f\u00fcr Trisomie-Tests\" \/>\n<meta name=\"twitter:description\" content=\"Nach einer Entscheidung des Gemeinsamen Bundesausschusses sollen Krankenkassen in Einzelf\u00e4llen wie Risikoschwangerschaften die Kosten f\u00fcr Trisomie-Bluttests \u00fcbernehmen ... | 25. September 2019\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/09\/Bluttest2.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@omniquestbonn\" \/>\n<meta name=\"twitter:site\" content=\"@omniquestbonn\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"maxkunz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\\\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\\\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests\"},\"author\":{\"name\":\"maxkunz\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#\\\/schema\\\/person\\\/cc5f4802f3fe5782ee50302f6421626f\"},\"headline\":\"65% bef\u00fcrworten Kosten\u00fcbernahme durch Krankenkassen f\u00fcr Trisomie-Tests\",\"datePublished\":\"2019-09-25T10:56:28+00:00\",\"dateModified\":\"2019-09-25T10:56:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\\\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests\"},\"wordCount\":359,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\\\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Bluttest2.jpg\",\"keywords\":[\"bluttest\",\"geld\",\"krankenkasse\",\"schwangerschaft\",\"trisomie\"],\"articleSection\":[\"Gesellschaft\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\\\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\\\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\\\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests\",\"name\":\"Umfrage - Kosten\u00fcbernahme von Trisomie-Test durch Krankenkassen?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\\\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\\\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Bluttest2.jpg\",\"datePublished\":\"2019-09-25T10:56:28+00:00\",\"dateModified\":\"2019-09-25T10:56:32+00:00\",\"description\":\"Umfrage zum Thema Trisomie-Test - ... Entscheidung des Bundesausschusses ... Krankenkassen ... die Kosten f\u00fcr Trisomie-Bluttests \u00fcbernehmen ...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\\\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\\\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\\\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#primaryimage\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Bluttest2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Bluttest2.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"umfrage trisomie test\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\\\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Umfragen\",\"item\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gesellschaft\",\"item\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/gesellschaft\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"65% bef\u00fcrworten Kosten\u00fcbernahme durch Krankenkassen f\u00fcr Trisomie-Tests\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#website\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/\",\"name\":\"OmniQuest News\",\"description\":\"Das Portal f\u00fcr News aus der Marktforschung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#organization\",\"name\":\"OmniQuest\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/OmniQuest-Logo_Green.png\",\"contentUrl\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/OmniQuest-Logo_Green.png\",\"width\":1000,\"height\":254,\"caption\":\"OmniQuest\"},\"image\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/omniquest\",\"https:\\\/\\\/x.com\\\/omniquestbonn\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#\\\/schema\\\/person\\\/cc5f4802f3fe5782ee50302f6421626f\",\"name\":\"maxkunz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g\",\"caption\":\"maxkunz\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Umfrage - Kosten\u00fcbernahme von Trisomie-Test durch Krankenkassen?","description":"Umfrage zum Thema Trisomie-Test - ... Entscheidung des Bundesausschusses ... Krankenkassen ... die Kosten f\u00fcr Trisomie-Bluttests \u00fcbernehmen ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests","og_locale":"de_DE","og_type":"article","og_title":"OmniQuest-Umfrage: 65% bef\u00fcrworten Kosten\u00fcbernahme durch Krankenkassen f\u00fcr Trisomie-Tests","og_description":"Nach einer Entscheidung des Gemeinsamen Bundesausschusses sollen Krankenkassen in Einzelf\u00e4llen wie Risikoschwangerschaften die Kosten f\u00fcr Trisomie-Bluttests \u00fcbernehmen ... | 25. September 2019","og_url":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests","og_site_name":"OmniQuest News","article_publisher":"https:\/\/www.facebook.com\/omniquest","article_published_time":"2019-09-25T10:56:28+00:00","article_modified_time":"2019-09-25T10:56:32+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/09\/Bluttest2.jpg","type":"image\/jpeg"}],"author":"maxkunz","twitter_card":"summary_large_image","twitter_title":"OmniQuest-Umfrage: 65% bef\u00fcrworten Kosten\u00fcbernahme durch Krankenkassen f\u00fcr Trisomie-Tests","twitter_description":"Nach einer Entscheidung des Gemeinsamen Bundesausschusses sollen Krankenkassen in Einzelf\u00e4llen wie Risikoschwangerschaften die Kosten f\u00fcr Trisomie-Bluttests \u00fcbernehmen ... | 25. September 2019","twitter_image":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/09\/Bluttest2.jpg","twitter_creator":"@omniquestbonn","twitter_site":"@omniquestbonn","twitter_misc":{"Verfasst von":"maxkunz","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#article","isPartOf":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests"},"author":{"name":"maxkunz","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#\/schema\/person\/cc5f4802f3fe5782ee50302f6421626f"},"headline":"65% bef\u00fcrworten Kosten\u00fcbernahme durch Krankenkassen f\u00fcr Trisomie-Tests","datePublished":"2019-09-25T10:56:28+00:00","dateModified":"2019-09-25T10:56:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests"},"wordCount":359,"commentCount":0,"publisher":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#organization"},"image":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#primaryimage"},"thumbnailUrl":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/09\/Bluttest2.jpg","keywords":["bluttest","geld","krankenkasse","schwangerschaft","trisomie"],"articleSection":["Gesellschaft"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests","url":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests","name":"Umfrage - Kosten\u00fcbernahme von Trisomie-Test durch Krankenkassen?","isPartOf":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#primaryimage"},"image":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#primaryimage"},"thumbnailUrl":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/09\/Bluttest2.jpg","datePublished":"2019-09-25T10:56:28+00:00","dateModified":"2019-09-25T10:56:32+00:00","description":"Umfrage zum Thema Trisomie-Test - ... Entscheidung des Bundesausschusses ... Krankenkassen ... die Kosten f\u00fcr Trisomie-Bluttests \u00fcbernehmen ...","breadcrumb":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#primaryimage","url":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/09\/Bluttest2.jpg","contentUrl":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/09\/Bluttest2.jpg","width":1920,"height":1280,"caption":"umfrage trisomie test"},{"@type":"BreadcrumbList","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft\/65-befuerworten-kostenuebernahme-durch-krankenkassen-fuer-trisomie-tests#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.omniquest.de\/marktforschung-news"},{"@type":"ListItem","position":2,"name":"Umfragen","item":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen"},{"@type":"ListItem","position":3,"name":"Gesellschaft","item":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/gesellschaft"},{"@type":"ListItem","position":4,"name":"65% bef\u00fcrworten Kosten\u00fcbernahme durch Krankenkassen f\u00fcr Trisomie-Tests"}]},{"@type":"WebSite","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#website","url":"https:\/\/www.omniquest.de\/marktforschung-news\/","name":"OmniQuest News","description":"Das Portal f\u00fcr News aus der Marktforschung","publisher":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.omniquest.de\/marktforschung-news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#organization","name":"OmniQuest","url":"https:\/\/www.omniquest.de\/marktforschung-news\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#\/schema\/logo\/image\/","url":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/02\/OmniQuest-Logo_Green.png","contentUrl":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/02\/OmniQuest-Logo_Green.png","width":1000,"height":254,"caption":"OmniQuest"},"image":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/omniquest","https:\/\/x.com\/omniquestbonn"]},{"@type":"Person","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#\/schema\/person\/cc5f4802f3fe5782ee50302f6421626f","name":"maxkunz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g","caption":"maxkunz"}}]}},"_links":{"self":[{"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/posts\/36348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/comments?post=36348"}],"version-history":[{"count":4,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/posts\/36348\/revisions"}],"predecessor-version":[{"id":36354,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/posts\/36348\/revisions\/36354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/media\/36351"}],"wp:attachment":[{"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/media?parent=36348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/categories?post=36348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/tags?post=36348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}