{"id":36546,"date":"2019-11-15T11:58:24","date_gmt":"2019-11-15T10:58:24","guid":{"rendered":"https:\/\/www.omniquest.de\/marktforschung-news\/?p=36546"},"modified":"2019-11-15T11:58:28","modified_gmt":"2019-11-15T10:58:28","slug":"46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab","status":"publish","type":"post","link":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab","title":{"rendered":"46% lehnen Steuervorteile f\u00fcr reine M\u00e4nner-Vereine ab"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;3.22&#8243; bb_built=&#8220;1&#8243; _i=&#8220;0&#8243; _address=&#8220;0&#8243;][et_pb_row _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; _i=&#8220;0&#8243; _address=&#8220;0.0&#8243;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; _i=&#8220;0&#8243; _address=&#8220;0.0.0&#8243; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Fragetext&#8220; _builder_version=&#8220;3.29.3&#8243; hover_enabled=&#8220;0&#8243; border_style=&#8220;solid&#8220; _i=&#8220;0&#8243; _address=&#8220;0.0.0.0&#8243;]\t<\/p>\n<p>In Deutschland gibt es zahlreiche Vereine wie Sch\u00fctzengilden, Sportclubs oder Gesangsvereine, die nur M\u00e4nner als Mitglieder aufnehmen. Bundesfinanzminister Olaf Scholz (SPD) will diesen das Recht auf Gemeinn\u00fctzigkeit entziehen und Steuervorteile streichen. Die Anerkennung der Gemeinn\u00fctzigkeit ist Voraussetzung f\u00fcr Steuervorteile. Die CSU ist dagegen, Vereine steuerlich zu benachteiligen, wenn sich ihr Angebot nur an Frauen oder nur an M\u00e4nner richtet. Wie stehen Sie zu diesem Thema? Steuervorteile f\u00fcr reine M\u00e4nner-Vereine\u2026[\/et_pb_text][et_pb_counters bar_bg_color=&#8220;#38b400&#8243; _builder_version=&#8220;3.29.3&#8243; hover_enabled=&#8220;0&#8243; border_style=&#8220;solid&#8220; border_radius=&#8220;0&#8243; _i=&#8220;1&#8243; _address=&#8220;0.0.0.1&#8243;][et_pb_counter percent=&#8220;38&#8243; _builder_version=&#8220;3.29.3&#8243; title_font=&#8220;||||&#8220; percent_font=&#8220;||||&#8220; hover_enabled=&#8220;0&#8243; background_color_default=&#8220;#dddddd&#8220; parallax_default=&#8220;off&#8220; parallax_method_default=&#8220;on&#8220; bar_background_color_default=&#8220;#38b400&#8243; use_percentages=&#8220;on&#8220; border_radius=&#8220;0&#8243; allow_player_pause_default=&#8220;off&#8220; _i=&#8220;0&#8243; _address=&#8220;0.0.0.1.0&#8243; background_enable_color_default=&#8220;on&#8220;]<\/p>\n<p>bef\u00fcrworte ich<\/p>\n<p>[\/et_pb_counter][et_pb_counter percent=&#8220;46&#8243; _builder_version=&#8220;3.29.3&#8243; title_font=&#8220;||||&#8220; percent_font=&#8220;||||&#8220; hover_enabled=&#8220;0&#8243; background_color_default=&#8220;#dddddd&#8220; parallax_default=&#8220;off&#8220; parallax_method_default=&#8220;on&#8220; bar_background_color_default=&#8220;#38b400&#8243; use_percentages=&#8220;on&#8220; border_radius=&#8220;0&#8243; allow_player_pause_default=&#8220;off&#8220; _i=&#8220;1&#8243; _address=&#8220;0.0.0.1.1&#8243; background_enable_color_default=&#8220;on&#8220;]<\/p>\n<p>lehne ich ab<\/p>\n<p>[\/et_pb_counter][et_pb_counter percent=&#8220;16&#8243; _builder_version=&#8220;3.29.3&#8243; title_font=&#8220;||||&#8220; percent_font=&#8220;||||&#8220; hover_enabled=&#8220;0&#8243; background_color_default=&#8220;#dddddd&#8220; parallax_default=&#8220;off&#8220; parallax_method_default=&#8220;on&#8220; bar_background_color_default=&#8220;#38b400&#8243; use_percentages=&#8220;on&#8220; border_radius=&#8220;0&#8243; allow_player_pause_default=&#8220;off&#8220; _i=&#8220;2&#8243; _address=&#8220;0.0.0.1.2&#8243; background_enable_color_default=&#8220;on&#8220;]Bin mir nicht sicher[\/et_pb_counter][\/et_pb_counters][et_pb_text _builder_version=&#8220;3.29.3&#8243; hover_enabled=&#8220;0&#8243; border_style=&#8220;solid&#8220; _i=&#8220;2&#8243; _address=&#8220;0.0.0.2&#8243;]<\/p>\n<p>331 Teilnehmer<\/p>\n<p>Erhebungszeitraum: 11.11.2019 \u2013 15.11.2019<\/p>\n<p><span style=\"color: #ff8b00;\">Der Quick Poll ist ein Instrument zur kurzfristigen Trendmessung unter beliebigen Teilnehmern aus dem <a class=\"news_beitrag_link\" href=\"http:\/\/www.omniquest.de\/omnipanel\">OmniPanel<\/a> und beansprucht keine <a class=\"news_beitrag_link\" href=\"http:\/\/www.omniquest.de\/repraesentativitaet\">Repr\u00e4sentativit\u00e4t<\/a> f\u00fcr sich.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Deutschland gibt es zahlreiche Vereine wie Sch\u00fctzengilden, Sportclubs oder Gesangsvereine, die nur M\u00e4nner als Mitglieder aufnehmen. Bundesfinanzminister Olaf Scholz (SPD) will diesen das Recht auf Gemeinn\u00fctzigkeit entziehen und Steuervorteile streichen. Die Anerkennung der Gemeinn\u00fctzigkeit ist Voraussetzung f\u00fcr Steuervorteile. Die CSU ist dagegen, Vereine steuerlich zu benachteiligen, wenn sich ihr Angebot nur an Frauen oder [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36549,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[17],"tags":[104,81,766,463,321,767],"class_list":["post-36546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-cdu","tag-csu","tag-maennervereine","tag-scholz","tag-steuern","tag-steuervorteile","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e4nnervereine - Recht auf Gemeinn\u00fctzigkeit entziehen?<\/title>\n<meta name=\"description\" content=\"Olaf Scholz (SPD) will M\u00e4nner-Vereinen das Recht auf Gemeinn\u00fctzigkeit entziehen und Steuervorteile streichen - OmniQuest Umfrage\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OmniQuest-Umfrage: 46% lehnen Steuervorteile f\u00fcr reine M\u00e4nner-Vereine ab\" \/>\n<meta property=\"og:description\" content=\"In Deutschland gibt es zahlreiche Vereine wie Sch\u00fctzengilden, Sportclubs oder Gesangsvereine, die nur M\u00e4nner als Mitglieder aufnehmen. Bundesfinanzminister Olaf Scholz (SPD) will ... | 15. November 2019\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab\" \/>\n<meta property=\"og:site_name\" content=\"OmniQuest News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/omniquest\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-15T10:58:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-15T10:58:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/11\/m\u00e4nnervereine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1271\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maxkunz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"OmniQuest-Umfrage: 46% lehnen Steuervorteile f\u00fcr reine M\u00e4nner-Vereine ab\" \/>\n<meta name=\"twitter:description\" content=\"In Deutschland gibt es zahlreiche Vereine wie Sch\u00fctzengilden, Sportclubs oder Gesangsvereine, die nur M\u00e4nner als Mitglieder aufnehmen. Bundesfinanzminister Olaf Scholz (SPD) will ... | 15. November 2019\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/11\/m\u00e4nnervereine.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@omniquestbonn\" \/>\n<meta name=\"twitter:site\" content=\"@omniquestbonn\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"maxkunz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab\"},\"author\":{\"name\":\"maxkunz\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#\\\/schema\\\/person\\\/cc5f4802f3fe5782ee50302f6421626f\"},\"headline\":\"46% lehnen Steuervorteile f\u00fcr reine M\u00e4nner-Vereine ab\",\"datePublished\":\"2019-11-15T10:58:24+00:00\",\"dateModified\":\"2019-11-15T10:58:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab\"},\"wordCount\":369,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/m\u00e4nnervereine.jpg\",\"keywords\":[\"cdu\",\"csu\",\"m\u00e4nnervereine\",\"scholz\",\"steuern\",\"steuervorteile\"],\"articleSection\":[\"Politik\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab\",\"name\":\"M\u00e4nnervereine - Recht auf Gemeinn\u00fctzigkeit entziehen?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/m\u00e4nnervereine.jpg\",\"datePublished\":\"2019-11-15T10:58:24+00:00\",\"dateModified\":\"2019-11-15T10:58:28+00:00\",\"description\":\"Olaf Scholz (SPD) will M\u00e4nner-Vereinen das Recht auf Gemeinn\u00fctzigkeit entziehen und Steuervorteile streichen - OmniQuest Umfrage\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#primaryimage\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/m\u00e4nnervereine.jpg\",\"contentUrl\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/m\u00e4nnervereine.jpg\",\"width\":1920,\"height\":1271,\"caption\":\"M\u00e4nnervereine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Umfragen\",\"item\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Politik\",\"item\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"46% lehnen Steuervorteile f\u00fcr reine M\u00e4nner-Vereine ab\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#website\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/\",\"name\":\"OmniQuest News\",\"description\":\"Das Portal f\u00fcr News aus der Marktforschung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#organization\",\"name\":\"OmniQuest\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/OmniQuest-Logo_Green.png\",\"contentUrl\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/OmniQuest-Logo_Green.png\",\"width\":1000,\"height\":254,\"caption\":\"OmniQuest\"},\"image\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/omniquest\",\"https:\\\/\\\/x.com\\\/omniquestbonn\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#\\\/schema\\\/person\\\/cc5f4802f3fe5782ee50302f6421626f\",\"name\":\"maxkunz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g\",\"caption\":\"maxkunz\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e4nnervereine - Recht auf Gemeinn\u00fctzigkeit entziehen?","description":"Olaf Scholz (SPD) will M\u00e4nner-Vereinen das Recht auf Gemeinn\u00fctzigkeit entziehen und Steuervorteile streichen - OmniQuest Umfrage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab","og_locale":"de_DE","og_type":"article","og_title":"OmniQuest-Umfrage: 46% lehnen Steuervorteile f\u00fcr reine M\u00e4nner-Vereine ab","og_description":"In Deutschland gibt es zahlreiche Vereine wie Sch\u00fctzengilden, Sportclubs oder Gesangsvereine, die nur M\u00e4nner als Mitglieder aufnehmen. Bundesfinanzminister Olaf Scholz (SPD) will ... | 15. November 2019","og_url":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab","og_site_name":"OmniQuest News","article_publisher":"https:\/\/www.facebook.com\/omniquest","article_published_time":"2019-11-15T10:58:24+00:00","article_modified_time":"2019-11-15T10:58:28+00:00","og_image":[{"width":1920,"height":1271,"url":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/11\/m\u00e4nnervereine.jpg","type":"image\/jpeg"}],"author":"maxkunz","twitter_card":"summary_large_image","twitter_title":"OmniQuest-Umfrage: 46% lehnen Steuervorteile f\u00fcr reine M\u00e4nner-Vereine ab","twitter_description":"In Deutschland gibt es zahlreiche Vereine wie Sch\u00fctzengilden, Sportclubs oder Gesangsvereine, die nur M\u00e4nner als Mitglieder aufnehmen. Bundesfinanzminister Olaf Scholz (SPD) will ... | 15. November 2019","twitter_image":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/11\/m\u00e4nnervereine.jpg","twitter_creator":"@omniquestbonn","twitter_site":"@omniquestbonn","twitter_misc":{"Verfasst von":"maxkunz","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#article","isPartOf":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab"},"author":{"name":"maxkunz","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#\/schema\/person\/cc5f4802f3fe5782ee50302f6421626f"},"headline":"46% lehnen Steuervorteile f\u00fcr reine M\u00e4nner-Vereine ab","datePublished":"2019-11-15T10:58:24+00:00","dateModified":"2019-11-15T10:58:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab"},"wordCount":369,"commentCount":0,"publisher":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#organization"},"image":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#primaryimage"},"thumbnailUrl":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/11\/m\u00e4nnervereine.jpg","keywords":["cdu","csu","m\u00e4nnervereine","scholz","steuern","steuervorteile"],"articleSection":["Politik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab","url":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab","name":"M\u00e4nnervereine - Recht auf Gemeinn\u00fctzigkeit entziehen?","isPartOf":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#primaryimage"},"image":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#primaryimage"},"thumbnailUrl":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/11\/m\u00e4nnervereine.jpg","datePublished":"2019-11-15T10:58:24+00:00","dateModified":"2019-11-15T10:58:28+00:00","description":"Olaf Scholz (SPD) will M\u00e4nner-Vereinen das Recht auf Gemeinn\u00fctzigkeit entziehen und Steuervorteile streichen - OmniQuest Umfrage","breadcrumb":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#primaryimage","url":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/11\/m\u00e4nnervereine.jpg","contentUrl":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/11\/m\u00e4nnervereine.jpg","width":1920,"height":1271,"caption":"M\u00e4nnervereine"},{"@type":"BreadcrumbList","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-lehnen-steuervorteile-fuer-reine-maenner-vereine-ab#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.omniquest.de\/marktforschung-news"},{"@type":"ListItem","position":2,"name":"Umfragen","item":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen"},{"@type":"ListItem","position":3,"name":"Politik","item":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik"},{"@type":"ListItem","position":4,"name":"46% lehnen Steuervorteile f\u00fcr reine M\u00e4nner-Vereine ab"}]},{"@type":"WebSite","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#website","url":"https:\/\/www.omniquest.de\/marktforschung-news\/","name":"OmniQuest News","description":"Das Portal f\u00fcr News aus der Marktforschung","publisher":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.omniquest.de\/marktforschung-news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#organization","name":"OmniQuest","url":"https:\/\/www.omniquest.de\/marktforschung-news\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#\/schema\/logo\/image\/","url":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/02\/OmniQuest-Logo_Green.png","contentUrl":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/02\/OmniQuest-Logo_Green.png","width":1000,"height":254,"caption":"OmniQuest"},"image":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/omniquest","https:\/\/x.com\/omniquestbonn"]},{"@type":"Person","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#\/schema\/person\/cc5f4802f3fe5782ee50302f6421626f","name":"maxkunz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g","caption":"maxkunz"}}]}},"_links":{"self":[{"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/posts\/36546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/comments?post=36546"}],"version-history":[{"count":2,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/posts\/36546\/revisions"}],"predecessor-version":[{"id":36550,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/posts\/36546\/revisions\/36550"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/media\/36549"}],"wp:attachment":[{"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/media?parent=36546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/categories?post=36546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/tags?post=36546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}