{"id":39004,"date":"2022-12-15T10:05:56","date_gmt":"2022-12-15T09:05:56","guid":{"rendered":"https:\/\/www.omniquest.de\/marktforschung-news\/?p=39004"},"modified":"2022-12-15T10:59:16","modified_gmt":"2022-12-15T09:59:16","slug":"46-befuerworten-erleichterte-fachkraeftezuwanderung","status":"publish","type":"post","link":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung","title":{"rendered":"46% bef\u00fcrworten erleichterte Fachkr\u00e4ftezuwanderung"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Fragetext&#8220; _builder_version=&#8220;4.19.0&#8243; border_style=&#8220;solid&#8220; global_colors_info=&#8220;{}&#8220;]Die Bundesregierung will die Einwanderung von qualifizierten Arbeitskr\u00e4ften aus dem Ausland deutlich erleichtern, um gegen den Fachkr\u00e4ftemangel vorzugehen. Anerkannte Fachkr\u00e4fte mit einem g\u00fcltigen Arbeitsvertrag sowie Fachkr\u00e4fte ohne einen Arbeitsvertrag sollen bei nachgewiesener Eignung einfacher als bisher nach Deutschland kommen k\u00f6nnen. Die Opposition \u00e4u\u00dfert sich skeptisch und bem\u00e4ngelt die Nichtaussch\u00f6pfung bereits vorhandener Potenziale. Wie stehen Sie zu einer erleichterten Fachkr\u00e4ftezuwanderung?[\/et_pb_text][et_pb_counters bar_bg_color=&#8220;#38b400&#8243; _builder_version=&#8220;4.19.0&#8243; border_style=&#8220;solid&#8220; border_radius=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_counter percent=&#8220;46&#8243; _builder_version=&#8220;4.19.0&#8243; title_font=&#8220;||||&#8220; percent_font=&#8220;||||&#8220; global_colors_info=&#8220;{}&#8220; bar_background_color_default=&#8220;#38b400&#8243; use_percentages=&#8220;on&#8220; border_radius=&#8220;0&#8243;]Bef\u00fcrworte ich[\/et_pb_counter][et_pb_counter percent=&#8220;41&#8243; _builder_version=&#8220;4.19.0&#8243; title_font=&#8220;||||&#8220; percent_font=&#8220;||||&#8220; global_colors_info=&#8220;{}&#8220; bar_background_color_default=&#8220;#38b400&#8243; use_percentages=&#8220;on&#8220; border_radius=&#8220;0&#8243;]Lehne ich ab[\/et_pb_counter][et_pb_counter percent=&#8220;13&#8243; _builder_version=&#8220;4.19.0&#8243; title_font=&#8220;||||&#8220; percent_font=&#8220;||||&#8220; global_colors_info=&#8220;{}&#8220; bar_background_color_default=&#8220;#38b400&#8243; use_percentages=&#8220;on&#8220; border_radius=&#8220;0&#8243;]Bin mir nicht sicher[\/et_pb_counter][\/et_pb_counters][et_pb_text _builder_version=&#8220;4.19.0&#8243; hover_enabled=&#8220;0&#8243; border_style=&#8220;solid&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p>435 Teilnehmer<\/p>\n<p>Erhebungszeitraum: 30.11.2022 \u2013 14.12.2022<\/p>\n<p><span style=\"color: #ff8b00;\">Der Quick Poll ist ein Instrument zur kurzfristigen Trendmessung unter beliebigen Teilnehmern aus dem <a class=\"news_beitrag_link\" href=\"http:\/\/www.omniquest.de\/omnipanel\">OmniPanel<\/a> und beansprucht keine Repr\u00e4sentativit\u00e4t f\u00fcr sich.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Bundesregierung will die Einwanderung von qualifizierten Arbeitskr\u00e4ften aus dem Ausland deutlich erleichtern, um gegen den Fachkr\u00e4ftemangel vorzugehen. Anerkannte Fachkr\u00e4fte mit einem g\u00fcltigen Arbeitsvertrag sowie Fachkr\u00e4fte ohne einen Arbeitsvertrag sollen bei nachgewiesener Eignung einfacher als bisher nach Deutschland kommen k\u00f6nnen. Die Opposition \u00e4u\u00dfert sich skeptisch und bem\u00e4ngelt die Nichtaussch\u00f6pfung bereits vorhandener Potenziale. Wie stehen Sie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":39007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[17,11],"tags":[],"class_list":["post-39004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","category-wirtschaft","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fachkr\u00e4ftedebatte | OmniQuest Umfrage<\/title>\n<meta name=\"description\" content=\"Die Bundesregierung will die Einwanderung von qualifizierten Arbeitskr\u00e4ften aus dem Ausland deutlich erleichtern, um gegen den ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OmniQuest-Umfrage: 46% bef\u00fcrworten erleichterte Fachkr\u00e4ftezuwanderung\" \/>\n<meta property=\"og:description\" content=\"Die Bundesregierung will die Einwanderung von qualifizierten Arbeitskr\u00e4ften aus dem Ausland deutlich erleichtern, um gegen den Fachkr\u00e4ftemangel vorzugehen. Anerkannte Fachkr\u00e4fte ... | 15. Dezember 2022\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung\" \/>\n<meta property=\"og:site_name\" content=\"OmniQuest News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/omniquest\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-15T09:05:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-15T09:59:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2022\/12\/medic.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maxkunz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"OmniQuest-Umfrage: 46% bef\u00fcrworten erleichterte Fachkr\u00e4ftezuwanderung\" \/>\n<meta name=\"twitter:description\" content=\"Die Bundesregierung will die Einwanderung von qualifizierten Arbeitskr\u00e4ften aus dem Ausland deutlich erleichtern, um gegen den Fachkr\u00e4ftemangel vorzugehen. Anerkannte Fachkr\u00e4fte ... | 15. Dezember 2022\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2022\/12\/medic.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@omniquestbonn\" \/>\n<meta name=\"twitter:site\" content=\"@omniquestbonn\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"maxkunz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-befuerworten-erleichterte-fachkraeftezuwanderung#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-befuerworten-erleichterte-fachkraeftezuwanderung\"},\"author\":{\"name\":\"maxkunz\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#\\\/schema\\\/person\\\/cc5f4802f3fe5782ee50302f6421626f\"},\"headline\":\"46% bef\u00fcrworten erleichterte Fachkr\u00e4ftezuwanderung\",\"datePublished\":\"2022-12-15T09:05:56+00:00\",\"dateModified\":\"2022-12-15T09:59:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-befuerworten-erleichterte-fachkraeftezuwanderung\"},\"wordCount\":294,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-befuerworten-erleichterte-fachkraeftezuwanderung#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/medic.jpg\",\"articleSection\":[\"Politik\",\"Wirtschaft\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-befuerworten-erleichterte-fachkraeftezuwanderung#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-befuerworten-erleichterte-fachkraeftezuwanderung\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-befuerworten-erleichterte-fachkraeftezuwanderung\",\"name\":\"Fachkr\u00e4ftedebatte | OmniQuest Umfrage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-befuerworten-erleichterte-fachkraeftezuwanderung#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-befuerworten-erleichterte-fachkraeftezuwanderung#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/medic.jpg\",\"datePublished\":\"2022-12-15T09:05:56+00:00\",\"dateModified\":\"2022-12-15T09:59:16+00:00\",\"description\":\"Die Bundesregierung will die Einwanderung von qualifizierten Arbeitskr\u00e4ften aus dem Ausland deutlich erleichtern, um gegen den ...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-befuerworten-erleichterte-fachkraeftezuwanderung#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-befuerworten-erleichterte-fachkraeftezuwanderung\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-befuerworten-erleichterte-fachkraeftezuwanderung#primaryimage\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/medic.jpg\",\"contentUrl\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/medic.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\\\/46-befuerworten-erleichterte-fachkraeftezuwanderung#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Umfragen\",\"item\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Politik\",\"item\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/aktuelle-umfragen\\\/politik\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"46% bef\u00fcrworten erleichterte Fachkr\u00e4ftezuwanderung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#website\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/\",\"name\":\"OmniQuest News\",\"description\":\"Das Portal f\u00fcr News aus der Marktforschung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#organization\",\"name\":\"OmniQuest\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/OmniQuest-Logo_Green.png\",\"contentUrl\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/OmniQuest-Logo_Green.png\",\"width\":1000,\"height\":254,\"caption\":\"OmniQuest\"},\"image\":{\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/omniquest\",\"https:\\\/\\\/x.com\\\/omniquestbonn\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.omniquest.de\\\/marktforschung-news\\\/#\\\/schema\\\/person\\\/cc5f4802f3fe5782ee50302f6421626f\",\"name\":\"maxkunz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g\",\"caption\":\"maxkunz\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fachkr\u00e4ftedebatte | OmniQuest Umfrage","description":"Die Bundesregierung will die Einwanderung von qualifizierten Arbeitskr\u00e4ften aus dem Ausland deutlich erleichtern, um gegen den ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung","og_locale":"de_DE","og_type":"article","og_title":"OmniQuest-Umfrage: 46% bef\u00fcrworten erleichterte Fachkr\u00e4ftezuwanderung","og_description":"Die Bundesregierung will die Einwanderung von qualifizierten Arbeitskr\u00e4ften aus dem Ausland deutlich erleichtern, um gegen den Fachkr\u00e4ftemangel vorzugehen. Anerkannte Fachkr\u00e4fte ... | 15. Dezember 2022","og_url":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung","og_site_name":"OmniQuest News","article_publisher":"https:\/\/www.facebook.com\/omniquest","article_published_time":"2022-12-15T09:05:56+00:00","article_modified_time":"2022-12-15T09:59:16+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2022\/12\/medic.jpg","type":"image\/jpeg"}],"author":"maxkunz","twitter_card":"summary_large_image","twitter_title":"OmniQuest-Umfrage: 46% bef\u00fcrworten erleichterte Fachkr\u00e4ftezuwanderung","twitter_description":"Die Bundesregierung will die Einwanderung von qualifizierten Arbeitskr\u00e4ften aus dem Ausland deutlich erleichtern, um gegen den Fachkr\u00e4ftemangel vorzugehen. Anerkannte Fachkr\u00e4fte ... | 15. Dezember 2022","twitter_image":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2022\/12\/medic.jpg","twitter_creator":"@omniquestbonn","twitter_site":"@omniquestbonn","twitter_misc":{"Verfasst von":"maxkunz","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung#article","isPartOf":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung"},"author":{"name":"maxkunz","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#\/schema\/person\/cc5f4802f3fe5782ee50302f6421626f"},"headline":"46% bef\u00fcrworten erleichterte Fachkr\u00e4ftezuwanderung","datePublished":"2022-12-15T09:05:56+00:00","dateModified":"2022-12-15T09:59:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung"},"wordCount":294,"commentCount":0,"publisher":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#organization"},"image":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung#primaryimage"},"thumbnailUrl":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2022\/12\/medic.jpg","articleSection":["Politik","Wirtschaft"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung","url":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung","name":"Fachkr\u00e4ftedebatte | OmniQuest Umfrage","isPartOf":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung#primaryimage"},"image":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung#primaryimage"},"thumbnailUrl":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2022\/12\/medic.jpg","datePublished":"2022-12-15T09:05:56+00:00","dateModified":"2022-12-15T09:59:16+00:00","description":"Die Bundesregierung will die Einwanderung von qualifizierten Arbeitskr\u00e4ften aus dem Ausland deutlich erleichtern, um gegen den ...","breadcrumb":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung#primaryimage","url":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2022\/12\/medic.jpg","contentUrl":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2022\/12\/medic.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik\/46-befuerworten-erleichterte-fachkraeftezuwanderung#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.omniquest.de\/marktforschung-news"},{"@type":"ListItem","position":2,"name":"Umfragen","item":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen"},{"@type":"ListItem","position":3,"name":"Politik","item":"https:\/\/www.omniquest.de\/marktforschung-news\/aktuelle-umfragen\/politik"},{"@type":"ListItem","position":4,"name":"46% bef\u00fcrworten erleichterte Fachkr\u00e4ftezuwanderung"}]},{"@type":"WebSite","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#website","url":"https:\/\/www.omniquest.de\/marktforschung-news\/","name":"OmniQuest News","description":"Das Portal f\u00fcr News aus der Marktforschung","publisher":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.omniquest.de\/marktforschung-news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#organization","name":"OmniQuest","url":"https:\/\/www.omniquest.de\/marktforschung-news\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#\/schema\/logo\/image\/","url":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/02\/OmniQuest-Logo_Green.png","contentUrl":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-content\/uploads\/2019\/02\/OmniQuest-Logo_Green.png","width":1000,"height":254,"caption":"OmniQuest"},"image":{"@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/omniquest","https:\/\/x.com\/omniquestbonn"]},{"@type":"Person","@id":"https:\/\/www.omniquest.de\/marktforschung-news\/#\/schema\/person\/cc5f4802f3fe5782ee50302f6421626f","name":"maxkunz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4263acc4a3ce0b258a5f70ea20a3e80c96ef22b12f62637ae28a3eebf4a0f094?s=96&d=mm&r=g","caption":"maxkunz"}}]}},"_links":{"self":[{"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/posts\/39004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/comments?post=39004"}],"version-history":[{"count":3,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/posts\/39004\/revisions"}],"predecessor-version":[{"id":39014,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/posts\/39004\/revisions\/39014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/media\/39007"}],"wp:attachment":[{"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/media?parent=39004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/categories?post=39004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.omniquest.de\/marktforschung-news\/wp-json\/wp\/v2\/tags?post=39004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}